{"id":26499,"date":"2023-07-06T10:16:19","date_gmt":"2023-07-06T09:16:19","guid":{"rendered":"http:\/\/lnx.radioascoli.it\/?p=26499"},"modified":"2023-07-06T10:16:19","modified_gmt":"2023-07-06T09:16:19","slug":"a-realta-locali-massimo-massetti","status":"publish","type":"post","link":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/","title":{"rendered":"A Realt\u00e0 Locali Massimo Massetti"},"content":{"rendered":"<p>&#8220;Forza Massimo!&#8221;<\/p>\n<p>Questo il grido proclamato durante le prove della Quintana di Luglio in onore della Madonna della Pace, che si sono tenute ieri presso il velodromo\u00a0 di Monticelli e che verr\u00e0 ripetuto al Campo de i Giochi dopo la proclamazione del vincitore della Giostra.<\/p>\n<p>Ne abbiamo parlato con Massimo Massetti, presidente del Consiglio degli Anziani, che ha sottolineato l&#8217;unit\u00e0 dimostrata da tutti i Sestieri in questo frangente cos\u00ec difficile.<\/p>\n<p>Ascolta l&#8217;intervista di Veruska Cestarelli, alle 12.30 e alle 18.30, anche in streaming.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Forza Massimo!&#8221; Questo il grido proclamato durante le prove della Quintana di Luglio in onore della Madonna della Pace, che si sono tenute ieri presso il velodromo\u00a0 di Monticelli e che verr\u00e0 ripetuto al Campo de i Giochi dopo la proclamazione del vincitore della Giostra. Ne abbiamo parlato con Massimo Massetti, presidente del Consiglio degli [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[3],"tags":[2558,3643,3644,4692],"series":[],"class_list":["post-26499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-forza-massimo","tag-massimo-gubbini-infortunio","tag-massimo-massetti","tag-prove-quintana-luglio-2023"],"episode_featured_image":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg","episode_player_image":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2024\/11\/Podcast-Domenica-cuore-della-comunita.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"soundcloud":{"key":"soundcloud","url":"","label":"SoundCloud","class":"soundcloud","icon":"soundcloud.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"}},"rssFeedUrl":"https:\/\/radioascoli.gleeze.com\/feed\/podcast\/domenica-cuore-della-comunita","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"f3QdbpJznG\"><a href=\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/\">A Realt\u00e0 Locali Massimo Massetti<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/embed\/#?secret=f3QdbpJznG\" width=\"500\" height=\"350\" title=\"&#8220;A Realt\u00e0 Locali Massimo Massetti&#8221; &#8212; Radio Ascoli\" data-secret=\"f3QdbpJznG\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/radioascoli.gleeze.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Realt\u00e0 Locali Massimo Massetti - Radio Ascoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Realt\u00e0 Locali Massimo Massetti - Radio Ascoli\" \/>\n<meta property=\"og:description\" content=\"&#8220;Forza Massimo!&#8221; Questo il grido proclamato durante le prove della Quintana di Luglio in onore della Madonna della Pace, che si sono tenute ieri presso il velodromo\u00a0 di Monticelli e che verr\u00e0 ripetuto al Campo de i Giochi dopo la proclamazione del vincitore della Giostra. Ne abbiamo parlato con Massimo Massetti, presidente del Consiglio degli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ascoli\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-06T09:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1294\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/\",\"url\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/\",\"name\":\"A Realt\u00e0 Locali Massimo Massetti - Radio Ascoli\",\"isPartOf\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg\",\"datePublished\":\"2023-07-06T09:16:19+00:00\",\"author\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb\"},\"breadcrumb\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#primaryimage\",\"url\":\"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg\",\"contentUrl\":\"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg\",\"width\":1294,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radioascoli.gleeze.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Realt\u00e0 Locali Massimo Massetti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/#website\",\"url\":\"https:\/\/radioascoli.gleeze.com\/\",\"name\":\"Radio Ascoli\",\"description\":\"La voce del Territorio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioascoli.gleeze.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/radioascoli.gleeze.com\/index.php\/author\/staff_radioap\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Realt\u00e0 Locali Massimo Massetti - Radio Ascoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/","og_locale":"it_IT","og_type":"article","og_title":"A Realt\u00e0 Locali Massimo Massetti - Radio Ascoli","og_description":"&#8220;Forza Massimo!&#8221; Questo il grido proclamato durante le prove della Quintana di Luglio in onore della Madonna della Pace, che si sono tenute ieri presso il velodromo\u00a0 di Monticelli e che verr\u00e0 ripetuto al Campo de i Giochi dopo la proclamazione del vincitore della Giostra. Ne abbiamo parlato con Massimo Massetti, presidente del Consiglio degli [&hellip;]","og_url":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/","og_site_name":"Radio Ascoli","article_published_time":"2023-07-06T09:16:19+00:00","og_image":[{"width":1294,"height":687,"url":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/","url":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/","name":"A Realt\u00e0 Locali Massimo Massetti - Radio Ascoli","isPartOf":{"@id":"https:\/\/radioascoli.gleeze.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#primaryimage"},"image":{"@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#primaryimage"},"thumbnailUrl":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg","datePublished":"2023-07-06T09:16:19+00:00","author":{"@id":"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb"},"breadcrumb":{"@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#primaryimage","url":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg","contentUrl":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2023\/07\/Prove-Quintana-forzaMassimo.jpg","width":1294,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2023\/07\/06\/a-realta-locali-massimo-massetti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radioascoli.gleeze.com\/"},{"@type":"ListItem","position":2,"name":"A Realt\u00e0 Locali Massimo Massetti"}]},{"@type":"WebSite","@id":"https:\/\/radioascoli.gleeze.com\/#website","url":"https:\/\/radioascoli.gleeze.com\/","name":"Radio Ascoli","description":"La voce del Territorio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioascoli.gleeze.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/radioascoli.gleeze.com\/index.php\/author\/staff_radioap\/"}]}},"_links":{"self":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/posts\/26499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/comments?post=26499"}],"version-history":[{"count":0,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/posts\/26499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/media\/26500"}],"wp:attachment":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/media?parent=26499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/categories?post=26499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/tags?post=26499"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/series?post=26499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}