{"id":27524,"date":"2024-04-04T10:34:20","date_gmt":"2024-04-04T09:34:20","guid":{"rendered":"http:\/\/lnx.radioascoli.it\/?p=27524"},"modified":"2024-04-04T10:34:20","modified_gmt":"2024-04-04T09:34:20","slug":"lascoli-calcio-si-salvera-parola-del-patron-pulcinelli","status":"publish","type":"post","link":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/","title":{"rendered":"&#8220;L&#8217;Ascoli calcio si salver\u00e0&#8221;, parola del patron Pulcinelli"},"content":{"rendered":"<p>Oggi a Realt\u00e0 locali ascolteremo alcuni interventi che il patron dell&#8217;Ascoli Massimo Pulcinelli ha rilasciato nel corso di una conferenza stampa che si \u00e8 tenuta presso la sede di Corso Vittorio Emanuele. Il patron bianconero si \u00e8 dichiarato sicuro della salvezza dell&#8217;Ascoli Calcio e dell&#8217;impossibilit\u00e0 di un eventuale fallimento del a Societ\u00e0 ed ha spiegato i motivi del cambio allenatore seguito all&#8217;esonero di mister Castori. Il tutto in attesa del Venezia al Del Duca Domenica 7 Aprile alle ore 16:15. <a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv x1fey0fg xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/realt%C3%A0locali?__eep__=6&amp;__cft__[0]=AZW78Iw1rAjtGYugpghA2d0kUYkMf2jDNspshxOmrqT8U1MOM1xZiblKNxXzj85kTjakjI3Qwp1GbHVigjx2oCad-iRYQcuYAlsw3O_ZwcsCPFcViit0EltLePKFFomunYc&amp;__tn__=*NK-R\">#realt\u00e0locali<\/a> su <a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv x1fey0fg xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/radioascoli?__eep__=6&amp;__cft__[0]=AZW78Iw1rAjtGYugpghA2d0kUYkMf2jDNspshxOmrqT8U1MOM1xZiblKNxXzj85kTjakjI3Qwp1GbHVigjx2oCad-iRYQcuYAlsw3O_ZwcsCPFcViit0EltLePKFFomunYc&amp;__tn__=*NK-R\">#radioascoli<\/a> ore 12.30 e 18.30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi a Realt\u00e0 locali ascolteremo alcuni interventi che il patron dell&#8217;Ascoli Massimo Pulcinelli ha rilasciato nel corso di una conferenza stampa che si \u00e8 tenuta presso la sede di Corso Vittorio Emanuele. Il patron bianconero si \u00e8 dichiarato sicuro della salvezza dell&#8217;Ascoli Calcio e dell&#8217;impossibilit\u00e0 di un eventuale fallimento del a Societ\u00e0 ed ha spiegato [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[3],"tags":[],"series":[],"class_list":["post-27524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"episode_featured_image":false,"episode_player_image":"https:\/\/radioascoli.gleeze.com\/wp-content\/uploads\/2024\/11\/Podcast-Domenica-cuore-della-comunita.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"soundcloud":{"key":"soundcloud","url":"","label":"SoundCloud","class":"soundcloud","icon":"soundcloud.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"}},"rssFeedUrl":"https:\/\/radioascoli.gleeze.com\/feed\/podcast\/domenica-cuore-della-comunita","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"h9LhUzMvTw\"><a href=\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/\">&#8220;L&#8217;Ascoli calcio si salver\u00e0&#8221;, parola del patron Pulcinelli<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/embed\/#?secret=h9LhUzMvTw\" width=\"500\" height=\"350\" title=\"&#8220;&#8220;L&#8217;Ascoli calcio si salver\u00e0&#8221;, parola del patron Pulcinelli&#8221; &#8212; Radio Ascoli\" data-secret=\"h9LhUzMvTw\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/radioascoli.gleeze.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;L&#039;Ascoli calcio si salver\u00e0&quot;, parola del patron Pulcinelli - Radio Ascoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;L&#039;Ascoli calcio si salver\u00e0&quot;, parola del patron Pulcinelli - Radio Ascoli\" \/>\n<meta property=\"og:description\" content=\"Oggi a Realt\u00e0 locali ascolteremo alcuni interventi che il patron dell&#8217;Ascoli Massimo Pulcinelli ha rilasciato nel corso di una conferenza stampa che si \u00e8 tenuta presso la sede di Corso Vittorio Emanuele. Il patron bianconero si \u00e8 dichiarato sicuro della salvezza dell&#8217;Ascoli Calcio e dell&#8217;impossibilit\u00e0 di un eventuale fallimento del a Societ\u00e0 ed ha spiegato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ascoli\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T09:34:20+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/\",\"url\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/\",\"name\":\"\\\"L'Ascoli calcio si salver\u00e0\\\", parola del patron Pulcinelli - Radio Ascoli\",\"isPartOf\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-04-04T09:34:20+00:00\",\"author\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb\"},\"breadcrumb\":{\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radioascoli.gleeze.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;L&#8217;Ascoli calcio si salver\u00e0&#8221;, parola del patron Pulcinelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/#website\",\"url\":\"https:\/\/radioascoli.gleeze.com\/\",\"name\":\"Radio Ascoli\",\"description\":\"La voce del Territorio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioascoli.gleeze.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/radioascoli.gleeze.com\/index.php\/author\/staff_radioap\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"L'Ascoli calcio si salver\u00e0\", parola del patron Pulcinelli - Radio Ascoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/","og_locale":"it_IT","og_type":"article","og_title":"\"L'Ascoli calcio si salver\u00e0\", parola del patron Pulcinelli - Radio Ascoli","og_description":"Oggi a Realt\u00e0 locali ascolteremo alcuni interventi che il patron dell&#8217;Ascoli Massimo Pulcinelli ha rilasciato nel corso di una conferenza stampa che si \u00e8 tenuta presso la sede di Corso Vittorio Emanuele. Il patron bianconero si \u00e8 dichiarato sicuro della salvezza dell&#8217;Ascoli Calcio e dell&#8217;impossibilit\u00e0 di un eventuale fallimento del a Societ\u00e0 ed ha spiegato [&hellip;]","og_url":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/","og_site_name":"Radio Ascoli","article_published_time":"2024-04-04T09:34:20+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/","url":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/","name":"\"L'Ascoli calcio si salver\u00e0\", parola del patron Pulcinelli - Radio Ascoli","isPartOf":{"@id":"https:\/\/radioascoli.gleeze.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#primaryimage"},"image":{"@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-04-04T09:34:20+00:00","author":{"@id":"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb"},"breadcrumb":{"@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/radioascoli.gleeze.com\/index.php\/2024\/04\/04\/lascoli-calcio-si-salvera-parola-del-patron-pulcinelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radioascoli.gleeze.com\/"},{"@type":"ListItem","position":2,"name":"&#8220;L&#8217;Ascoli calcio si salver\u00e0&#8221;, parola del patron Pulcinelli"}]},{"@type":"WebSite","@id":"https:\/\/radioascoli.gleeze.com\/#website","url":"https:\/\/radioascoli.gleeze.com\/","name":"Radio Ascoli","description":"La voce del Territorio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioascoli.gleeze.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/951d8fdb6b4c932dd7e4085356de2cfb","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/radioascoli.gleeze.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b40962913816192011daa5088aab2e8a8b3011a7e4adc13ba8e540d97e8c7467?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/radioascoli.gleeze.com\/index.php\/author\/staff_radioap\/"}]}},"_links":{"self":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/posts\/27524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/comments?post=27524"}],"version-history":[{"count":0,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/posts\/27524\/revisions"}],"wp:attachment":[{"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/media?parent=27524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/categories?post=27524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/tags?post=27524"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/radioascoli.gleeze.com\/index.php\/wp-json\/wp\/v2\/series?post=27524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}